{"id":15911,"date":"2024-06-26T14:53:48","date_gmt":"2024-06-26T12:53:48","guid":{"rendered":"https:\/\/www.cornea-franz.de\/?post_type=encyclopedia&#038;p=15911"},"modified":"2024-07-08T16:18:29","modified_gmt":"2024-07-08T14:18:29","slug":"it-litigation","status":"publish","type":"encyclopedia","link":"https:\/\/www.cornea-franz.de\/es\/glossar\/it-litigation\/","title":{"rendered":"IT-Litigation"},"content":{"rendered":"<p>Mit dem englischen Begriff &bdquo;Litigation&ldquo; wird das Durchsetzen oder Abwehren von Anspr&uuml;chen vor Gericht bezeichnet. &bdquo;IT-Litigation&ldquo; bezeichnet also die Prozessf&uuml;hrung betreffend Anspr&uuml;che aus (gescheiterten) Gesch&auml;ftsbeziehungen, die aus einem IT-Projekt herr&uuml;hren (z.B. <a href=\"https:\/\/www.cornea-franz.de\/es\/glossar\/softwarelizenzen\/\" target=\"_blank\" title=\"Unter einer &bdquo;Lizenz&ldquo; wird landl&auml;ufig ein Nutzungsrecht verstanden. Weil dieser Begriff aber gesetzlich im deutschen Recht nicht n&auml;her definiert ist und Nutzungs- und Verwertungsrechte sehr grob oder sehr fein ausdefiniert werden k&ouml;nnen, sagt der Begriff selbst &uuml;ber den Umfang einer Lizenz erst einmal gar nichts aus. Problematisch kann das werden, wenn zwei Vertragsparteien jeweils sehr klare aber voneinander stark abweichende Vorstellungen davon haben, was sie unter einer Lizenz verstehen bzw. was sie davon umfasst sehen. Da Nutzungsrechte f&uuml;r Software im Urheberrechtsgesetz (UrhG) geregelt sind, kann die richtige Formulierung einer Lizenz starke Folgen f&uuml;r die wirtschaftliche Verwertung oder den Umfang von&hellip;\" class=\"encyclopedia\">Softwarelizenzen<\/a>, <a href=\"https:\/\/www.cornea-franz.de\/es\/glossar\/softwareentwicklung\/\" target=\"_blank\" title=\"Die Entwicklung von Software geschieht durch sogenannten Programmieren. Dabei schreiben Entwickler\/Softwareentwickler den sogenannten Quellcode meist in einer menschenlesbaren Programmiersprache. Dieser Quellcode wird dann meist mittels sogenannter Compiler in maschinenlesbaren und von Maschinen (Computern) ausf&uuml;hrbaren Code &uuml;bersetzt. Bei der Beurteilung der Frage, wem die Rechte an dem vom Entwickler geschriebenen Quellcode zustehen, sind neben urheberrechtlichen und arbeitsrechtlichen Fragen oft auch allgemeine Auslegungsgrunds&auml;tze zu beachten.\" class=\"encyclopedia\">Softwareentwicklung<\/a>, Softwareberatung, Hardwareberatung, Hardwarekauf, Hardwaremiete, o.&auml;.). Dabei sind die prozessualen Besonderheiten des Sachvortrags und der Beweisf&uuml;hrung zu den komplexen Sachverhalten aus IT-Projekten zu beachten, die eine gro&szlig;e Menge an Erfahrung und Sorgfalt f&uuml;rs Detail voraussetzen.<\/p>\n","protected":false},"author":2,"template":"","encyclopedia-category":[712],"encyclopedia-tag":[],"class_list":["post-15911","encyclopedia","type-encyclopedia","status-publish","hentry","encyclopedia-category-it-recht"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia\/15911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/media?parent=15911"}],"wp:term":[{"taxonomy":"encyclopedia-category","embeddable":true,"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia-category?post=15911"},{"taxonomy":"encyclopedia-tag","embeddable":true,"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia-tag?post=15911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}