{"id":21071,"date":"2025-09-09T11:53:32","date_gmt":"2025-09-09T09:53:32","guid":{"rendered":"https:\/\/www.cornea-franz.de\/?post_type=encyclopedia&#038;p=21071"},"modified":"2025-09-09T11:58:46","modified_gmt":"2025-09-09T09:58:46","slug":"boesglaeubige-markenanmeldung","status":"publish","type":"encyclopedia","link":"https:\/\/www.cornea-franz.de\/es\/glossar\/boesglaeubige-markenanmeldung\/","title":{"rendered":"B\u00f6sgl\u00e4ubige Markenanmeldung"},"content":{"rendered":"<p>Eine <a href=\"https:\/\/www.cornea-franz.de\/es\/glossar\/markenanmeldung\/\" target=\"_blank\" title=\"Die Markenanmeldung ist der formelle Prozess zur Eintragung einer Marke in das Markenregister. Hierbei muss der Anmelder das gew&uuml;nschte Zeichen (Wort, Bild oder Logo) sowie die Waren und Dienstleistung angeben, f&uuml;r welche die Marke genutzt werden soll. Nach Pr&uuml;fung durch das zust&auml;ndige Amt, wie das Deutsche Patent- und Markenamt (DPMA), wird die Marke eingetragen und genie&szlig;t dann Markenschutz, wenn nicht Dritte innerhalb der Widerspruchsfrist Widerspruch gegen die Marke einlegen. Fehler bei der Anmeldung, wie ungenaue Waren- oder Dienstleistungsangaben, k&ouml;nnen den Schutzumfang beeintr&auml;chtigen.\" class=\"encyclopedia\">Markenanmeldung<\/a> in b&ouml;ser Absicht liegt vor, wenn jemand ein Zeichen nur anmeldet, um andere zu blockieren oder zu erpressen (sog. &bdquo;Sperrmarken&ldquo;). Solche Marken k&ouml;nnen auf Antrag gel&ouml;scht werden. B&ouml;sgl&auml;ubigkeit ist ein h&auml;ufiger Streitpunkt bei Markenverletzungsverfahren und L&ouml;schungsverfahren.<\/p>\n<p>Praxisfrage: Was kann man tun, wenn jemand meine <a href=\"https:\/\/www.cornea-franz.de\/es\/glossar\/marke\/\" target=\"_blank\" title=\"Eine Marke ist ein rechtlich gesch&uuml;tztes Kennzeichen, das dazu dient, Waren oder Dienstleistungen eines Unternehmens von denen anderer Unternehmen zu unterscheiden. Sie kann aus W&ouml;rtern, Buchstaben, Zahlen, Farben, Bildern, Kl&auml;ngen oder sogar dreidimensionalen Formen bestehen. Marken schaffen Identit&auml;t, Vertrauen und Wiedererkennbarkeit f&uuml;r ein Unternehmen und sind ein zentrales Element des wirtschaftlichen Erfolgs.\" class=\"encyclopedia\">Marke<\/a> gekapert hat? &ndash;&nbsp; L&ouml;schungsantrag wegen b&ouml;sgl&auml;ubiger Anmeldung stellen.<\/p>\n","protected":false},"author":2,"template":"","encyclopedia-category":[782,711,780],"encyclopedia-tag":[1078],"class_list":["post-21071","encyclopedia","type-encyclopedia","status-publish","hentry","encyclopedia-category-gewerblicher-rechtsschutz","encyclopedia-category-markenrecht","encyclopedia-category-urheberrecht","encyclopedia-tag-boesglaeubige-markenanmeldung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia\/21071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia"}],"about":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/types\/encyclopedia"}],"author":[{"embeddable":true,"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/users\/2"}],"wp:attachment":[{"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/media?parent=21071"}],"wp:term":[{"taxonomy":"encyclopedia-category","embeddable":true,"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia-category?post=21071"},{"taxonomy":"encyclopedia-tag","embeddable":true,"href":"https:\/\/www.cornea-franz.de\/es\/wp-json\/wp\/v2\/encyclopedia-tag?post=21071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}